{"id":9102,"date":"2022-06-14T20:26:53","date_gmt":"2022-06-14T18:26:53","guid":{"rendered":"https:\/\/labonacarn.com\/producte\/pack-verbena-de-sant-joan-6-persones\/"},"modified":"2024-06-17T17:42:51","modified_gmt":"2024-06-17T15:42:51","slug":"pack-verbena","status":"publish","type":"product","link":"https:\/\/labonacarn.com\/es\/producte\/pack-verbena\/","title":{"rendered":"Pack verbena de Sant Joan (6 personas)"},"content":{"rendered":"<h2>Pack verbena de Sant Joan<\/h2>\n<p>Nuestro pack verbena de Sant Joan pensado para 6 personas. Como\u00a0 ingredientes principales tenemos jam\u00f3n ib\u00e9rico, jam\u00f3n dulce, nuestras croquetas, queso de cabra, nuestra espectacular longaniza, catalana y nuestra tortilla de patatas.<br \/>\nTodo en su justa medida, tan s\u00f3lo falta poner el pan de coca, tomate y un buen aceite. La bebida, a gusto del personal.<br \/>\nSeguro que es un gran pack para una gran verbena !!!<br \/>\nPrecio: 48\u20ac<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un gran pack para una gran verbena !!!<\/p>\n","protected":false},"featured_media":5866,"template":"","meta":{"_acf_changed":false,"_joinchat":[]},"product_brand":[],"product_cat":[63,65,115,106],"product_tag":[196,134,208,209],"class_list":["post-9102","product","type-product","status-publish","has-post-thumbnail","product_cat-carne","product_cat-la-despensa","product_cat-packs-es","product_cat-tengo-invitados","product_tag-amigos-es","product_tag-barbacoa-es","product_tag-barbacoas","product_tag-verbena","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pack verbena de Sant Joan (6 personas) - labonacarn.com<\/title>\n<meta name=\"description\" content=\"Pack para la verbena de San Juan, amenizado con nuestros mejores embutidos y productos de nuestra despensa, para pasar una noche inovidable!!!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/labonacarn.com\/es\/producte\/pack-verbena\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pack verbena de Sant Joan\" \/>\n<meta property=\"og:description\" content=\"El pack para tu verbena para 6 pesonas. No hace falta nada, tan solo tus invitados. Lo tienes bien f\u00e1cil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/labonacarn.com\/es\/producte\/pack-verbena\/\" \/>\n<meta property=\"og:site_name\" content=\"labonacarn.com\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-17T15:42:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/labonacarn.com\/wp-content\/uploads\/2022\/06\/focs-ciutat-horitzontal-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Pack verbena de Sant Joan\" \/>\n<meta name=\"twitter:description\" content=\"El pack para tu verbena para 6 pesonas. No hace falta nada, tan solo tus invitados. Lo tienes bien f\u00e1cil.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/labonacarn.com\/wp-content\/uploads\/2022\/06\/focs-ciutat-horitzontal-1.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/labonacarn.com\\\/es\\\/producte\\\/pack-verbena\\\/\",\"url\":\"https:\\\/\\\/labonacarn.com\\\/es\\\/producte\\\/pack-verbena\\\/\",\"name\":\"Pack verbena de Sant Joan (6 personas) - labonacarn.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/labonacarn.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/labonacarn.com\\\/es\\\/producte\\\/pack-verbena\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/labonacarn.com\\\/es\\\/producte\\\/pack-verbena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/labonacarn.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/focs-ciutat-horitzontal-1.jpg\",\"datePublished\":\"2022-06-14T18:26:53+00:00\",\"dateModified\":\"2024-06-17T15:42:51+00:00\",\"description\":\"Pack para la verbena de San Juan, amenizado con nuestros mejores embutidos y productos de nuestra despensa, para pasar una noche inovidable!!!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/labonacarn.com\\\/es\\\/producte\\\/pack-verbena\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/labonacarn.com\\\/es\\\/producte\\\/pack-verbena\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/labonacarn.com\\\/es\\\/producte\\\/pack-verbena\\\/#primaryimage\",\"url\":\"https:\\\/\\\/labonacarn.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/focs-ciutat-horitzontal-1.jpg\",\"contentUrl\":\"https:\\\/\\\/labonacarn.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/focs-ciutat-horitzontal-1.jpg\",\"width\":696,\"height\":500,\"caption\":\"Revetlla de Sant Joan\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/labonacarn.com\\\/es\\\/producte\\\/pack-verbena\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/labonacarn.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/labonacarn.com\\\/es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pack verbena de Sant Joan (6 personas)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/labonacarn.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/labonacarn.com\\\/es\\\/\",\"name\":\"labonacarn.com\",\"description\":\"Venem carn de vedella, porc, pollastre, xai, poltre, gall dindi i embotits de primera qualitat i fets per nosaltres.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/labonacarn.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pack verbena de Sant Joan (6 personas) - labonacarn.com","description":"Pack para la verbena de San Juan, amenizado con nuestros mejores embutidos y productos de nuestra despensa, para pasar una noche inovidable!!!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/labonacarn.com\/es\/producte\/pack-verbena\/","og_locale":"es_ES","og_type":"article","og_title":"Pack verbena de Sant Joan","og_description":"El pack para tu verbena para 6 pesonas. No hace falta nada, tan solo tus invitados. Lo tienes bien f\u00e1cil.","og_url":"https:\/\/labonacarn.com\/es\/producte\/pack-verbena\/","og_site_name":"labonacarn.com","article_modified_time":"2024-06-17T15:42:51+00:00","og_image":[{"url":"https:\/\/labonacarn.com\/wp-content\/uploads\/2022\/06\/focs-ciutat-horitzontal-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Pack verbena de Sant Joan","twitter_description":"El pack para tu verbena para 6 pesonas. No hace falta nada, tan solo tus invitados. Lo tienes bien f\u00e1cil.","twitter_image":"https:\/\/labonacarn.com\/wp-content\/uploads\/2022\/06\/focs-ciutat-horitzontal-1.jpg","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/labonacarn.com\/es\/producte\/pack-verbena\/","url":"https:\/\/labonacarn.com\/es\/producte\/pack-verbena\/","name":"Pack verbena de Sant Joan (6 personas) - labonacarn.com","isPartOf":{"@id":"https:\/\/labonacarn.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/labonacarn.com\/es\/producte\/pack-verbena\/#primaryimage"},"image":{"@id":"https:\/\/labonacarn.com\/es\/producte\/pack-verbena\/#primaryimage"},"thumbnailUrl":"https:\/\/labonacarn.com\/wp-content\/uploads\/2022\/06\/focs-ciutat-horitzontal-1.jpg","datePublished":"2022-06-14T18:26:53+00:00","dateModified":"2024-06-17T15:42:51+00:00","description":"Pack para la verbena de San Juan, amenizado con nuestros mejores embutidos y productos de nuestra despensa, para pasar una noche inovidable!!!","breadcrumb":{"@id":"https:\/\/labonacarn.com\/es\/producte\/pack-verbena\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/labonacarn.com\/es\/producte\/pack-verbena\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/labonacarn.com\/es\/producte\/pack-verbena\/#primaryimage","url":"https:\/\/labonacarn.com\/wp-content\/uploads\/2022\/06\/focs-ciutat-horitzontal-1.jpg","contentUrl":"https:\/\/labonacarn.com\/wp-content\/uploads\/2022\/06\/focs-ciutat-horitzontal-1.jpg","width":696,"height":500,"caption":"Revetlla de Sant Joan"},{"@type":"BreadcrumbList","@id":"https:\/\/labonacarn.com\/es\/producte\/pack-verbena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/labonacarn.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/labonacarn.com\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Pack verbena de Sant Joan (6 personas)"}]},{"@type":"WebSite","@id":"https:\/\/labonacarn.com\/es\/#website","url":"https:\/\/labonacarn.com\/es\/","name":"labonacarn.com","description":"Venem carn de vedella, porc, pollastre, xai, poltre, gall dindi i embotits de primera qualitat i fets per nosaltres.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/labonacarn.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/labonacarn.com\/es\/wp-json\/wp\/v2\/product\/9102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labonacarn.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/labonacarn.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labonacarn.com\/es\/wp-json\/wp\/v2\/media\/5866"}],"wp:attachment":[{"href":"https:\/\/labonacarn.com\/es\/wp-json\/wp\/v2\/media?parent=9102"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/labonacarn.com\/es\/wp-json\/wp\/v2\/product_brand?post=9102"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/labonacarn.com\/es\/wp-json\/wp\/v2\/product_cat?post=9102"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/labonacarn.com\/es\/wp-json\/wp\/v2\/product_tag?post=9102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}